{"id":23474,"date":"2026-05-12T16:10:58","date_gmt":"2026-05-12T19:10:58","guid":{"rendered":"https:\/\/www.bahiananoticias.com.br\/v1\/?p=23474"},"modified":"2026-05-12T16:10:58","modified_gmt":"2026-05-12T19:10:58","slug":"deputada-soane-galvao-e-marao-solicitam-obras-importantes-para-a-educacao-na-bahia","status":"publish","type":"post","link":"https:\/\/www.bahiananoticias.com.br\/v1\/2026\/05\/12\/deputada-soane-galvao-e-marao-solicitam-obras-importantes-para-a-educacao-na-bahia\/","title":{"rendered":"Deputada Soane Galv\u00e3o e Mar\u00e3o solicitam  obras importantes para a educa\u00e7\u00e3o na Bahia"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.bahiananoticias.com.br\/v1\/wp-content\/uploads\/2026\/05\/b2855fed-2f28-4686-98cd-b691242d6336.jpeg\" alt=\"\" width=\"600\" height=\"338\" class=\"alignnone size-full wp-image-23475\" srcset=\"https:\/\/www.bahiananoticias.com.br\/v1\/wp-content\/uploads\/2026\/05\/b2855fed-2f28-4686-98cd-b691242d6336.jpeg 600w, https:\/\/www.bahiananoticias.com.br\/v1\/wp-content\/uploads\/2026\/05\/b2855fed-2f28-4686-98cd-b691242d6336-300x169.jpeg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>A deputada estadual Soane Galv\u00e3o e o pr\u00e9-candidato a deputado estadual M\u00e1rio Alexandre, Mar\u00e3o, participaram na manh\u00e3 desta ter\u00e7a-feira(12) de uma audi\u00eancia com secret\u00e1ria estadual de Educa\u00e7\u00e3o, Luciana Menezes, onde foram discutidos, dentre outros assuntos,  sobre a conclus\u00e3o das obras do Col\u00e9gio da Pol\u00edcia Militar R\u00f4mulo Galv\u00e3o, em Ilh\u00e9us, manuten\u00e7\u00e3o da estrutura do pr\u00e9dio antigo da unidade, renova\u00e7\u00e3o do conv\u00eanio da Escola Municipal Cantinho do Recreio, no CSU, na Barra, entrega de emendas de \u00f4nibus escolares e kits tecnol\u00f3gicos, transfer\u00eancia do CPM de Itabuna para o CIEBTEC e a defini\u00e7\u00e3o da \u00e1rea para a constru\u00e7\u00e3o da Escola de Tempo Integral no munic\u00edpio de Una. <\/p>\n<p>Com rela\u00e7\u00e3o \u00e0s obras de conclus\u00e3o do CPM de Ilh\u00e9us, solicitadas por Mar\u00e3o e Soane Galv\u00e3o, a secret\u00e1ria Luciana Menezes informou que est\u00e3o bastante aceleradas e dever\u00e3o ser entregues em breve pelo governador Jer\u00f4nimo Rodrigues. Mar\u00e3o e Saane tamb\u00e9m pediram que fosse feita uma reavalia\u00e7\u00e3o da decis\u00e3o de demoli\u00e7\u00e3o do antigo pr\u00e9dio do CPM de Ilh\u00e9us, destacando que o im\u00f3vel ainda possui potencial de reaproveitamento pela gest\u00e3o militar. <\/p>\n<p>No of\u00edcio entregue \u00e0 secret\u00e1ria de Educa\u00e7\u00e3o, Soane Galv\u00e3o e Mar\u00e3o sugerem que o espa\u00e7o possa abrigar setores administrativos, oficinas, cursos profissionalizantes e projetos sociais, fortalecendo a comunidade escolar e a atua\u00e7\u00e3o institucional do CPM. Tamb\u00e9m ressaltaram que a reutiliza\u00e7\u00e3o do pr\u00e9dio seria uma alternativa economicamente vi\u00e1vel.<\/p>\n<p>Outra solicita\u00e7\u00e3o importante o do conv\u00eanio da Escola Municipal Cantinho do Recreio, no CSU da Barra, em Ilh\u00e9us, garantindo a continuidade das atividades escolares em 12 salas, j\u00e1 acordadas com o Governo do Estado, em benef\u00edcio dos estudantes e das fam\u00edlias da comunidade. O projeto foi aprovado ainda quando Mar\u00e3o era prefeito de Ilh\u00e9us, e o conv\u00eanio ficou pronto em 2025.  Segundo Luciana Menezes, a Secretaria Estadual de Educa\u00e7\u00e3o est\u00e1 h\u00e1 meses tentando alinhamento com a nova gest\u00e3o, sem sucesso. \u201cForam v\u00e1rios e-mails e liga\u00e7\u00f5es\u201d, explicou a secret\u00e1ria. \u201cEnquanto isso, os alunos est\u00e3o na Igreja porque n\u00e3o tem essa escola, que j\u00e1 era para estar pronta\u201d, complementou<\/p>\n<p>ITABUNA &#8211; Mar\u00e3o e Soane Galv\u00e3o tamb\u00e9m entregaram o of\u00edcio solicitando a transfer\u00eancia do CPM de Itabuna para o CIEBTEC, visando oferecer melhor estrutura f\u00edsica, tecnol\u00f3gica e pedag\u00f3gica para a comunidade escolar. De acordo com eles, a mudan\u00e7a trar\u00e1 mais qualidade ao ensino, a otimiza\u00e7\u00e3o dos recursos p\u00fablicos e melhores oportunidades para os estudantes. <\/p>\n<p>UNA &#8211; Outra solicita\u00e7\u00e3o importante foi a constru\u00e7\u00e3o da Escola de Tempo Integral no munic\u00edpio de Una. O impasse seria na escolha do terreno. Mar\u00e3o e Soane solicitaram o envio de uma nova equipe t\u00e9cnica para definirem um local que atenda todas as necessidades e viabilidades para que as obras sejam iniciadas o mais breve, entregando aos estudantes de Una uma escola bem equipada e moderna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A deputada estadual Soane Galv\u00e3o e o pr\u00e9-candidato a deputado estadual M\u00e1rio Alexandre, Mar\u00e3o, participaram na manh\u00e3 desta ter\u00e7a-feira(12) de uma audi\u00eancia com secret\u00e1ria estadual de Educa\u00e7\u00e3o, Luciana Menezes, onde foram discutidos, dentre outros assuntos, sobre a conclus\u00e3o das obras do Col\u00e9gio da Pol\u00edcia Militar R\u00f4mulo Galv\u00e3o, em Ilh\u00e9us, manuten\u00e7\u00e3o da estrutura do pr\u00e9dio antigo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23475,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"views":7,"_links":{"self":[{"href":"https:\/\/www.bahiananoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/23474"}],"collection":[{"href":"https:\/\/www.bahiananoticias.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bahiananoticias.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bahiananoticias.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bahiananoticias.com.br\/v1\/wp-json\/wp\/v2\/comments?post=23474"}],"version-history":[{"count":1,"href":"https:\/\/www.bahiananoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/23474\/revisions"}],"predecessor-version":[{"id":23476,"href":"https:\/\/www.bahiananoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/23474\/revisions\/23476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bahiananoticias.com.br\/v1\/wp-json\/wp\/v2\/media\/23475"}],"wp:attachment":[{"href":"https:\/\/www.bahiananoticias.com.br\/v1\/wp-json\/wp\/v2\/media?parent=23474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bahiananoticias.com.br\/v1\/wp-json\/wp\/v2\/categories?post=23474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bahiananoticias.com.br\/v1\/wp-json\/wp\/v2\/tags?post=23474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}